{"id":30930,"date":"2024-12-19T13:25:46","date_gmt":"2024-12-19T13:25:46","guid":{"rendered":"https:\/\/jemediguard.com\/?page_id=30930"},"modified":"2024-12-20T10:06:51","modified_gmt":"2024-12-20T10:06:51","slug":"guedel-airways","status":"publish","type":"page","link":"https:\/\/jemediguard.com\/index.php\/guedel-airways\/","title":{"rendered":"GUEDEL AIRWAYS"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"30930\" class=\"elementor elementor-30930\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-53d1d9a elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"53d1d9a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-c35912d\" data-id=\"c35912d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-50a9ff8 elementor-widget elementor-widget-shortcode\" data-id=\"50a9ff8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><button class=\"bellows-menu-toggle bellows-menu-toggle-skin-none\" aria-controls=\"bellows-main-87\"><i class=\"fa fa-bars\"><\/i> <span class=\"bellows-menu-toggle-text\">Menu<\/span><\/button><div id=\"bellows-main-87\" class=\"bellows bellows-nojs bellows-main bellows-source-menu bellows-align-full bellows-skin-none bellows-type- bellows-expand-current bellows-mobile-collapse\"><ul id=\"menu-mobile-categoies\" class=\"bellows-nav\" data-bellows-config=\"main\"><li id=\"menu-item-11891\" class=\"bellows-menu-item bellows-menu-item-type-post_type bellows-menu-item-object-page bellows-menu-item-11891 bellows-item-level-0\"><a  href=\"https:\/\/jemediguard.com\/index.php\/surgical-instruments\/\" class=\"bellows-target\"><span class=\"bellows-target-title bellows-target-text\">SURGICAL INSTRUMENTS<\/span><\/a><\/li>\n<li id=\"menu-item-11894\" class=\"bellows-menu-item bellows-menu-item-type-post_type bellows-menu-item-object-page bellows-menu-item-11894 bellows-item-level-0\"><a  href=\"https:\/\/jemediguard.com\/index.php\/hospital-furniture-manufacturer\/\" class=\"bellows-target\"><span class=\"bellows-target-title bellows-target-text\">HOSPITAL FURNITURE<\/span><\/a><\/li>\n<li id=\"menu-item-11895\" class=\"bellows-menu-item bellows-menu-item-type-post_type bellows-menu-item-object-page bellows-menu-item-11895 bellows-item-level-0\"><a  href=\"https:\/\/jemediguard.com\/index.php\/hospital-holloware\/\" class=\"bellows-target\"><span class=\"bellows-target-title bellows-target-text\">HOSPITAL HOLLOWARE<\/span><\/a><\/li>\n<li id=\"menu-item-11896\" class=\"bellows-menu-item bellows-menu-item-type-post_type bellows-menu-item-object-page bellows-menu-item-11896 bellows-item-level-0\"><a  href=\"https:\/\/jemediguard.com\/index.php\/medical-autoclaves\/\" class=\"bellows-target\"><span class=\"bellows-target-title bellows-target-text\">MEDICAL AUTOCLAVES<\/span><\/a><\/li>\n<li id=\"menu-item-11908\" class=\"bellows-menu-item bellows-menu-item-type-post_type bellows-menu-item-object-page bellows-menu-item-11908 bellows-item-level-0\"><a  href=\"https:\/\/jemediguard.com\/index.php\/operation-theatre-table-2\/\" class=\"bellows-target\"><span class=\"bellows-target-title bellows-target-text\">OPERATION THEATRE TABLE<\/span><\/a><\/li>\n<li id=\"menu-item-11907\" class=\"bellows-menu-item bellows-menu-item-type-post_type bellows-menu-item-object-page bellows-menu-item-11907 bellows-item-level-0\"><a  href=\"https:\/\/jemediguard.com\/index.php\/operation-theatre-light-2\/\" class=\"bellows-target\"><span class=\"bellows-target-title bellows-target-text\">OPERATION THEATRE LIGHT<\/span><\/a><\/li>\n<li id=\"menu-item-11876\" class=\"bellows-menu-item bellows-menu-item-type-post_type bellows-menu-item-object-page bellows-menu-item-11876 bellows-item-level-0\"><a  href=\"https:\/\/jemediguard.com\/index.php\/suction-machines\/\" class=\"bellows-target\"><span class=\"bellows-target-title bellows-target-text\">SUCTION MACHINES<\/span><\/a><\/li>\n<li id=\"menu-item-11875\" class=\"bellows-menu-item bellows-menu-item-type-post_type bellows-menu-item-object-page bellows-menu-item-11875 bellows-item-level-0\"><a  href=\"https:\/\/jemediguard.com\/index.php\/anesthesia-machine\/\" class=\"bellows-target\"><span class=\"bellows-target-title bellows-target-text\">ANESTHESIA MACHINE<\/span><\/a><\/li>\n<li id=\"menu-item-11874\" class=\"bellows-menu-item bellows-menu-item-type-post_type bellows-menu-item-object-page bellows-menu-item-11874 bellows-item-level-0\"><a  href=\"https:\/\/jemediguard.com\/index.php\/diagnostic-equipment-instruments\/\" class=\"bellows-target\"><span class=\"bellows-target-title bellows-target-text\">DIAGNOSTIC EQUIPMENT &amp; INSTRUMENTS<\/span><\/a><\/li>\n<li id=\"menu-item-11873\" class=\"bellows-menu-item bellows-menu-item-type-post_type bellows-menu-item-object-page bellows-menu-item-11873 bellows-item-level-0\"><a  href=\"https:\/\/jemediguard.com\/index.php\/infant-baby-care-equipment\/\" class=\"bellows-target\"><span class=\"bellows-target-title bellows-target-text\">INFANT &amp; BABY CARE EQUIPMENT<\/span><\/a><\/li>\n<li id=\"menu-item-11872\" class=\"bellows-menu-item bellows-menu-item-type-post_type bellows-menu-item-object-page bellows-menu-item-11872 bellows-item-level-0\"><a  href=\"https:\/\/jemediguard.com\/index.php\/electro-medical-equipment\/\" class=\"bellows-target\"><span class=\"bellows-target-title bellows-target-text\">ELECTRO MEDICAL EQUIPMENT<\/span><\/a><\/li>\n<li id=\"menu-item-11870\" class=\"bellows-menu-item bellows-menu-item-type-post_type bellows-menu-item-object-page bellows-menu-item-11870 bellows-item-level-0\"><a  href=\"https:\/\/jemediguard.com\/index.php\/oxygen-therapy-equipment\/\" class=\"bellows-target\"><span class=\"bellows-target-title bellows-target-text\">OXYGEN THERAPY EQUIPMENT<\/span><\/a><\/li>\n<li id=\"menu-item-11869\" class=\"bellows-menu-item bellows-menu-item-type-post_type bellows-menu-item-object-page bellows-menu-item-11869 bellows-item-level-0\"><a  href=\"https:\/\/jemediguard.com\/index.php\/anesthesia-equipment\/\" class=\"bellows-target\"><span class=\"bellows-target-title bellows-target-text\">ANESTHESIA EQUIPMENT<\/span><\/a><\/li>\n<li id=\"menu-item-11868\" class=\"bellows-menu-item bellows-menu-item-type-post_type bellows-menu-item-object-page bellows-menu-item-11868 bellows-item-level-0\"><a  href=\"https:\/\/jemediguard.com\/index.php\/physiotherapy-equipment\/\" class=\"bellows-target\"><span class=\"bellows-target-title bellows-target-text\">PHYSIOTHERAPY EQUIPMENT<\/span><\/a><\/li>\n<li id=\"menu-item-11867\" class=\"bellows-menu-item bellows-menu-item-type-post_type bellows-menu-item-object-page bellows-menu-item-11867 bellows-item-level-0\"><a  href=\"https:\/\/jemediguard.com\/index.php\/medical-surgical-rubber-products\/\" class=\"bellows-target\"><span class=\"bellows-target-title bellows-target-text\">MEDICAL SURGICAL RUBBER PRODUCTS<\/span><\/a><\/li>\n<li id=\"menu-item-11866\" class=\"bellows-menu-item bellows-menu-item-type-post_type bellows-menu-item-object-page bellows-menu-item-11866 bellows-item-level-0\"><a  href=\"https:\/\/jemediguard.com\/index.php\/bio-medical-waste-equipment\/\" class=\"bellows-target\"><span class=\"bellows-target-title bellows-target-text\">BIO MEDICAL WASTE EQUIPMENT<\/span><\/a><\/li>\n<li id=\"menu-item-11865\" class=\"bellows-menu-item bellows-menu-item-type-post_type bellows-menu-item-object-page bellows-menu-item-11865 bellows-item-level-0\"><a  href=\"https:\/\/jemediguard.com\/index.php\/medical-nursing-models-charts\/\" class=\"bellows-target\"><span class=\"bellows-target-title bellows-target-text\">MEDICAL NURSING MODELS &amp; CHARTS<\/span><\/a><\/li>\n<li id=\"menu-item-11864\" class=\"bellows-menu-item bellows-menu-item-type-post_type bellows-menu-item-object-page bellows-menu-item-11864 bellows-item-level-0\"><a  href=\"https:\/\/jemediguard.com\/index.php\/cold-chain-equipment-vaccine-carrier\/\" class=\"bellows-target\"><span class=\"bellows-target-title bellows-target-text\">COLD CHAIN EQUIPMENT &amp; VACCINE CARRIER<\/span><\/a><\/li>\n<li id=\"menu-item-11863\" class=\"bellows-menu-item bellows-menu-item-type-post_type bellows-menu-item-object-page bellows-menu-item-11863 bellows-item-level-0\"><a  href=\"https:\/\/jemediguard.com\/index.php\/lab-equipment\/\" class=\"bellows-target\"><span class=\"bellows-target-title bellows-target-text\">LAB EQUIPMENT<\/span><\/a><\/li>\n<li id=\"menu-item-11862\" class=\"bellows-menu-item bellows-menu-item-type-post_type bellows-menu-item-object-page bellows-menu-item-11862 bellows-item-level-0\"><a  href=\"https:\/\/jemediguard.com\/index.php\/xray-equipment\/\" class=\"bellows-target\"><span class=\"bellows-target-title bellows-target-text\">XRAY\u00a0EQUIPMENT<\/span><\/a><\/li>\n<\/ul><\/div><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-eea4f6f\" data-id=\"eea4f6f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-68daf7a elementor-widget elementor-widget-bdt-image-magnifier\" data-id=\"68daf7a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bdt-image-magnifier.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t            <div data-settings=\"{&quot;type&quot;:&quot;standard&quot;,&quot;bigImageSrc&quot;:&quot;https:\\\/\\\/jemediguard.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/GUEDEL-AIRWAYS-1.jpg&quot;,&quot;smoothMove&quot;:true,&quot;preload&quot;:true,&quot;position&quot;:&quot;right&quot;,&quot;zoomSize&quot;:[480,300],&quot;offset&quot;:[0,0]}\" class=\"bdt-image-magnifier bdt-position-relative\">\n                <img decoding=\"async\" class=\"bdt-image-magnifier-image\" src=\"https:\/\/jemediguard.com\/wp-content\/uploads\/2024\/12\/GUEDEL-AIRWAYS-1.jpg\" alt=\"\">\n            <\/div>\n            \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-524233a\" data-id=\"524233a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-13ed185 elementor-widget elementor-widget-razzi-heading\" data-id=\"13ed185\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"razzi-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"razzi-heading-wrapper\"><h2 class=\"razzi-heading-title\"> GUEDEL AIRWAYS<\/h2><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0715528 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"0715528\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"line-height: 2;\"><strong>P<\/strong><b>roduct<\/b><\/span><b> <\/b><span style=\"font-weight: bold; line-height: 2;\">Name:- GUEDEL AIRWAYS<\/span><br \/><span style=\"font-weight: bold; line-height: 2;\">Category :- ANESTHESIA EQUIPMENT <\/span><\/p><p><strong style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif;\">JULLUNDUR ENTERPRISES\u00a0\/ JALANDHAR ENTERPRISES SURGICAL INDUSTRIES<\/strong><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-weight: var( --e-global-typography-text-font-weight );\">\u00a0is the manufacturer, supplier and exporter of Stainless Steel Surgical Instruments under its brand name\u00a0<\/span><strong style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif;\">MEDIGUARD<\/strong><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-weight: var( --e-global-typography-text-font-weight );\">.<\/span><\/p><p><strong>JULLUNDUR ENTERPRISES\u00a0\/ JALANDHAR ENTERPRISES SURGICAL INDUSTRIES<\/strong> is engaged in manufacturing, supplying &amp; exporting <strong>GUEDEL AIRWAYS<span style=\"line-height: 2;\">.<\/span><\/strong><\/p><p><strong>JULLUNDUR ENTERPRISES\u00a0\/ JALANDHAR ENTERPRISES SURGICAL INDUSTRIES<\/strong> is a <strong>ANESTHESIA EQUIPMENT<\/strong> manufacturer in India, <strong>ANESTHESIA EQUIPMENT<\/strong> supplier in India, <strong>ANESTHESIA EQUIPMENT<\/strong> exporter from India and also involved in <strong>ANESTHESIA EQUIPMENT<\/strong>\u00a0hospital supplies.<\/p><p><strong>JULLUNDUR ENTERPRISES\u00a0\/ JALANDHAR ENTERPRISES SURGICAL INDUSTRIES<\/strong> is <strong>GUEDEL AIRWAYS<\/strong> manufacturer in India, <strong>GUEDEL AIRWAYS <\/strong>supplier in India, <strong>GUEDEL AIRWAYS<\/strong><strong>\u00a0<\/strong>exporter from India and also involved in <strong>GUEDEL AIRWAYS<\/strong><strong>\u00a0<\/strong>hospital supplies.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77f81ac elementor-align-left elementor-widget elementor-widget-razzi-button\" data-id=\"77f81ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"razzi-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <a href=\"#\" class=\"razzi-button-link razzi-button\">\n\t\t\t\t\t\t\t\t\t<span class=\"razzi-button-text\">Enquiry Now<\/span>        <\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2aa7b8b elementor-widget elementor-widget-elementskit-social-media\" data-id=\"2aa7b8b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-social-media.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\t\t\t <ul class=\"ekit_social_media\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"elementor-repeater-item-34e04d0\">\n\t\t\t\t\t    <a href=\"https:\/\/facebook.com\" aria-label=\"Facebook\" class=\"facebook\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-facebook\"><\/i>\n                                                                                                            <\/a>\n                    <\/li>\n                    \t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"elementor-repeater-item-30c9dd1\">\n\t\t\t\t\t    <a href=\"https:\/\/facebook.com\" aria-label=\"Twitter\" class=\"twitter\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-twitter\"><\/i>\n                                                                                                            <\/a>\n                    <\/li>\n                    \t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"elementor-repeater-item-d6b177a\">\n\t\t\t\t\t    <a href=\"https:\/\/facebook.com\" aria-label=\"LinkedIn\" class=\"linkedin\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-linkedin\"><\/i>\n                                                                                                            <\/a>\n                    <\/li>\n                    \t\t\t\t\t\t\t<\/ul>\n\t\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>GUEDEL AIRWAYS Product Name:- GUEDEL AIRWAYSCategory :- ANESTHESIA EQUIPMENT JULLUNDUR ENTERPRISES\u00a0\/ JALANDHAR ENTERPRISES SURGICAL INDUSTRIES\u00a0is the manufacturer, supplier and exporter of Stainless Steel Surgical Instruments under its brand name\u00a0MEDIGUARD. JULLUNDUR ENTERPRISES\u00a0\/ JALANDHAR ENTERPRISES SURGICAL INDUSTRIES is engaged in manufacturing, supplying &amp; exporting GUEDEL AIRWAYS. JULLUNDUR ENTERPRISES\u00a0\/ JALANDHAR ENTERPRISES SURGICAL INDUSTRIES is a ANESTHESIA EQUIPMENT manufacturer [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-30930","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/jemediguard.com\/index.php\/wp-json\/wp\/v2\/pages\/30930","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jemediguard.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/jemediguard.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/jemediguard.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jemediguard.com\/index.php\/wp-json\/wp\/v2\/comments?post=30930"}],"version-history":[{"count":0,"href":"https:\/\/jemediguard.com\/index.php\/wp-json\/wp\/v2\/pages\/30930\/revisions"}],"wp:attachment":[{"href":"https:\/\/jemediguard.com\/index.php\/wp-json\/wp\/v2\/media?parent=30930"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}